{"id":166058,"date":"2026-07-15T15:08:22","date_gmt":"2026-07-15T13:08:22","guid":{"rendered":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/"},"modified":"2026-07-15T15:12:10","modified_gmt":"2026-07-15T13:12:10","slug":"police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne","status":"publish","type":"post","link":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/","title":{"rendered":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne"},"content":{"rendered":"<p>This <a href=\"https:\/\/www.tdg.ch\/geneve-la-police-lance-un-service-de-pre-plainte-en-ligne-942588264045\" target=\"_blank\">post<\/a> was originally published on <a href=\"https:\/\/partner-feeds.publishing.tamedia.ch\/rss\/tdg\/geneve\" target=\"_blank\">this site<\/a>.<\/p><div>La police cantonale genevoise lance un service de pr&eacute;plainte. Un passage au poste reste n&eacute;cessaire pour signer la plainte et obtenir l&rsquo;attestation d&rsquo;assurance.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>This post was originally published on this site.La police cantonale genevoise lance un service de pr&eacute;plainte. Un passage au poste reste n&eacute;cessaire pour signer la plainte et obtenir l&rsquo;attestation d&rsquo;assurance.<\/p>\n","protected":false},"author":1,"featured_media":166059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[97],"tags":[],"class_list":["post-166058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international-news"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La police cantonale genevoise lance un service de pr\u00e9plainte. Un passage au poste reste n\u00e9cessaire pour signer la plainte et obtenir l\u2019attestation d\u2019assurance.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Morgane RAVOUNA\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gen\u00e8ve Infos - Le site d&#039;informations de la r\u00e9gion genevoise\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne - Gen\u00e8ve Infos\" \/>\n\t\t<meta property=\"og:description\" content=\"La police cantonale genevoise lance un service de pr\u00e9plainte. Un passage au poste reste n\u00e9cessaire pour signer la plainte et obtenir l\u2019attestation d\u2019assurance.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/geneveinfos.ch\/wp-content\/uploads\/2025\/09\/Capture-decran-2025-09-18-a-16.52.08.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/geneveinfos.ch\/wp-content\/uploads\/2025\/09\/Capture-decran-2025-09-18-a-16.52.08.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"513\" \/>\n\t\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T13:08:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T13:12:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61576016541234\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne - Gen\u00e8ve Infos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La police cantonale genevoise lance un service de pr\u00e9plainte. Un passage au poste reste n\u00e9cessaire pour signer la plainte et obtenir l\u2019attestation d\u2019assurance.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/geneveinfos.ch\/wp-content\/uploads\/2025\/09\/Capture-decran-2025-09-18-a-16.52.08.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#blogposting\",\"name\":\"Police genevoise: Les victimes peuvent pr\\u00e9d\\u00e9poser plainte en ligne - Gen\\u00e8ve Infos\",\"headline\":\"Police genevoise: Les victimes peuvent pr\\u00e9d\\u00e9poser plainte en ligne\",\"author\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/author\\\/admin1380\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/geneveinfos.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/C8TGOttnK-iBk4rYvidbVf.jpg\",\"width\":1024,\"height\":768},\"datePublished\":\"2026-07-15T15:08:22+02:00\",\"dateModified\":\"2026-07-15T15:12:10+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#webpage\"},\"articleSection\":\"international\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/geneveinfos.ch\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/category\\\/news\\\/international-news\\\/#listItem\",\"name\":\"international\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/category\\\/news\\\/international-news\\\/#listItem\",\"position\":3,\"name\":\"international\",\"item\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/category\\\/news\\\/international-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#listItem\",\"name\":\"Police genevoise: Les victimes peuvent pr\\u00e9d\\u00e9poser plainte en ligne\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/category\\\/news\\\/#listItem\",\"name\":\"News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#listItem\",\"position\":4,\"name\":\"Police genevoise: Les victimes peuvent pr\\u00e9d\\u00e9poser plainte en ligne\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/category\\\/news\\\/international-news\\\/#listItem\",\"name\":\"international\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/#person\",\"name\":\"Morgane RAVOUNA\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd1e2e1e7cabf66754a14e2181bc3f67cd3c2b9403841e078411545fc405115b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Morgane RAVOUNA\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/author\\\/admin1380\\\/#author\",\"url\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/author\\\/admin1380\\\/\",\"name\":\"Morgane RAVOUNA\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd1e2e1e7cabf66754a14e2181bc3f67cd3c2b9403841e078411545fc405115b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Morgane RAVOUNA\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#webpage\",\"url\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/\",\"name\":\"Police genevoise: Les victimes peuvent pr\\u00e9d\\u00e9poser plainte en ligne - Gen\\u00e8ve Infos\",\"description\":\"La police cantonale genevoise lance un service de pr\\u00e9plainte. Un passage au poste reste n\\u00e9cessaire pour signer la plainte et obtenir l\\u2019attestation d\\u2019assurance.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/author\\\/admin1380\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/author\\\/admin1380\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/geneveinfos.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/C8TGOttnK-iBk4rYvidbVf.jpg\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#mainImage\",\"width\":1024,\"height\":768},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/index.php\\\/2026\\\/07\\\/15\\\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\\\/#mainImage\"},\"datePublished\":\"2026-07-15T15:08:22+02:00\",\"dateModified\":\"2026-07-15T15:12:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/#website\",\"url\":\"https:\\\/\\\/geneveinfos.ch\\\/\",\"name\":\"Gen\\u00e8ve Infos\",\"description\":\"Le site d'informations de la r\\u00e9gion genevoise\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/geneveinfos.ch\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne - Gen\u00e8ve Infos","description":"La police cantonale genevoise lance un service de pr\u00e9plainte. Un passage au poste reste n\u00e9cessaire pour signer la plainte et obtenir l\u2019attestation d\u2019assurance.","canonical_url":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#blogposting","name":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne - Gen\u00e8ve Infos","headline":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne","author":{"@id":"https:\/\/geneveinfos.ch\/index.php\/author\/admin1380\/#author"},"publisher":{"@id":"https:\/\/geneveinfos.ch\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/geneveinfos.ch\/wp-content\/uploads\/2026\/07\/C8TGOttnK-iBk4rYvidbVf.jpg","width":1024,"height":768},"datePublished":"2026-07-15T15:08:22+02:00","dateModified":"2026-07-15T15:12:10+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#webpage"},"isPartOf":{"@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#webpage"},"articleSection":"international"},{"@type":"BreadcrumbList","@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch#listItem","position":1,"name":"Home","item":"https:\/\/geneveinfos.ch","nextItem":{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/#listItem","name":"News"}},{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/#listItem","position":2,"name":"News","item":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/international-news\/#listItem","name":"international"},"previousItem":{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/international-news\/#listItem","position":3,"name":"international","item":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/international-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#listItem","name":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne"},"previousItem":{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/#listItem","name":"News"}},{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#listItem","position":4,"name":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne","previousItem":{"@type":"ListItem","@id":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/international-news\/#listItem","name":"international"}}]},{"@type":"Person","@id":"https:\/\/geneveinfos.ch\/#person","name":"Morgane RAVOUNA","image":{"@type":"ImageObject","@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/bd1e2e1e7cabf66754a14e2181bc3f67cd3c2b9403841e078411545fc405115b?s=96&d=mm&r=g","width":96,"height":96,"caption":"Morgane RAVOUNA"}},{"@type":"Person","@id":"https:\/\/geneveinfos.ch\/index.php\/author\/admin1380\/#author","url":"https:\/\/geneveinfos.ch\/index.php\/author\/admin1380\/","name":"Morgane RAVOUNA","image":{"@type":"ImageObject","@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/bd1e2e1e7cabf66754a14e2181bc3f67cd3c2b9403841e078411545fc405115b?s=96&d=mm&r=g","width":96,"height":96,"caption":"Morgane RAVOUNA"}},{"@type":"WebPage","@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#webpage","url":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/","name":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne - Gen\u00e8ve Infos","description":"La police cantonale genevoise lance un service de pr\u00e9plainte. Un passage au poste reste n\u00e9cessaire pour signer la plainte et obtenir l\u2019attestation d\u2019assurance.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/geneveinfos.ch\/#website"},"breadcrumb":{"@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#breadcrumblist"},"author":{"@id":"https:\/\/geneveinfos.ch\/index.php\/author\/admin1380\/#author"},"creator":{"@id":"https:\/\/geneveinfos.ch\/index.php\/author\/admin1380\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/geneveinfos.ch\/wp-content\/uploads\/2026\/07\/C8TGOttnK-iBk4rYvidbVf.jpg","@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#mainImage","width":1024,"height":768},"primaryImageOfPage":{"@id":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/#mainImage"},"datePublished":"2026-07-15T15:08:22+02:00","dateModified":"2026-07-15T15:12:10+02:00"},{"@type":"WebSite","@id":"https:\/\/geneveinfos.ch\/#website","url":"https:\/\/geneveinfos.ch\/","name":"Gen\u00e8ve Infos","description":"Le site d'informations de la r\u00e9gion genevoise","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/geneveinfos.ch\/#person"}}]},"og:locale":"fr_FR","og:site_name":"Gen\u00e8ve Infos - Le site d'informations de la r\u00e9gion genevoise","og:type":"article","og:title":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne - Gen\u00e8ve Infos","og:description":"La police cantonale genevoise lance un service de pr\u00e9plainte. Un passage au poste reste n\u00e9cessaire pour signer la plainte et obtenir l\u2019attestation d\u2019assurance.","og:url":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/","og:image":"https:\/\/geneveinfos.ch\/wp-content\/uploads\/2025\/09\/Capture-decran-2025-09-18-a-16.52.08.png","og:image:secure_url":"https:\/\/geneveinfos.ch\/wp-content\/uploads\/2025\/09\/Capture-decran-2025-09-18-a-16.52.08.png","og:image:width":513,"og:image:height":457,"article:published_time":"2026-07-15T13:08:22+00:00","article:modified_time":"2026-07-15T13:12:10+00:00","article:publisher":"https:\/\/www.facebook.com\/profile.php?id=61576016541234","twitter:card":"summary_large_image","twitter:title":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne - Gen\u00e8ve Infos","twitter:description":"La police cantonale genevoise lance un service de pr\u00e9plainte. Un passage au poste reste n\u00e9cessaire pour signer la plainte et obtenir l\u2019attestation d\u2019assurance.","twitter:image":"https:\/\/geneveinfos.ch\/wp-content\/uploads\/2025\/09\/Capture-decran-2025-09-18-a-16.52.08.png"},"aioseo_meta_data":{"post_id":"166058","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-07-15 13:12:39","updated":"2026-07-15 13:12:39","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/geneveinfos.ch\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/geneveinfos.ch\/index.php\/category\/news\/\" title=\"News\">News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/geneveinfos.ch\/index.php\/category\/news\/international-news\/\" title=\"international\">international<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPolice genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/geneveinfos.ch"},{"label":"News","link":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/"},{"label":"international","link":"https:\/\/geneveinfos.ch\/index.php\/category\/news\/international-news\/"},{"label":"Police genevoise: Les victimes peuvent pr\u00e9d\u00e9poser plainte en ligne","link":"https:\/\/geneveinfos.ch\/index.php\/2026\/07\/15\/police-genevoise-les-victimes-peuvent-predeposer-plainte-en-ligne\/"}],"_links":{"self":[{"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/posts\/166058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/comments?post=166058"}],"version-history":[{"count":1,"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/posts\/166058\/revisions"}],"predecessor-version":[{"id":166060,"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/posts\/166058\/revisions\/166060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/media\/166059"}],"wp:attachment":[{"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/media?parent=166058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/categories?post=166058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/geneveinfos.ch\/index.php\/wp-json\/wp\/v2\/tags?post=166058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}